{"id":1420,"date":"2017-06-26T19:17:14","date_gmt":"2017-06-26T17:17:14","guid":{"rendered":"http:\/\/afk-lembach.at\/niederranna\/?p=1420"},"modified":"2017-07-17T19:21:33","modified_gmt":"2017-07-17T17:21:33","slug":"o-oe-landeswasserwehrleistungsbewerb-in-mitterkirchen","status":"publish","type":"post","link":"https:\/\/afk-lembach.at\/niederranna\/2017\/06\/26\/o-oe-landeswasserwehrleistungsbewerb-in-mitterkirchen\/","title":{"rendered":"O.\u00d6. Landeswasserwehrleistungsbewerb in Mitterkirchen"},"content":{"rendered":"<p>Am 23 &amp; 24. Juni 2017 veranstalteten die Feuerwehren H\u00fctting, Langacker und Mitterkirchen den diesj\u00e4hrigen Landeswasserwehrleistungsbewerb \u00a0auf der Donau in Mitterkirchen<\/p>\n<p>Bei sehr hei\u00dfen Wetterbedingungen gab es dieses Jahr einen neuen Teilnehmerrekord von \u00fcber 1000 Zillenbesatzungen.<\/p>\n<p>Wir gratulieren allen teilgenommenen Zillenbesatzungen f\u00fcr Ihre hervorragenden Leistungen.<\/p>\n<p><u>Besonders gratulieren d\u00fcrfen wir:<\/u><\/p>\n<p>3.Platz Bronze allgemeine Klasse B:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Engelbert Lang und Gerhard Sch\u00f6ngruber<\/p>\n<p><a href=\"http:\/\/www.ooelfv.at\/bewerbe-leistungspruefungen\/aktuelles\/bewerbsuebersicht\/#\/details\/1421\"><u>Ergebnislisten<\/u><\/a><\/p>\n<p><img decoding=\"async\" class=\"ngg-singlepic ngg-center\" src=\"https:\/\/afk-lembach.at\/niederranna\/wp-content\/blogs.dir\/10\/files\/landeswasserwehrleistungsbewerb-2017\/Landeswasserwehrleistungsbewerb2017_18.jpg\" alt=\"OLYMPUS DIGITAL CAMERA\" \/><\/p>\n<p><a href=\"https:\/\/afk-lembach.at\/niederranna\/bilder\/nggallery\/alles\/Landeswasserwehrleistungsbewerb-2017\">weiter Bilder<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 23 &amp; 24. Juni 2017 veranstalteten die Feuerwehren H\u00fctting, Langacker und Mitterkirchen den diesj\u00e4hrigen Landeswasserwehrleistungsbewerb \u00a0auf der Donau in Mitterkirchen Bei sehr hei\u00dfen Wetterbedingungen gab es dieses Jahr einen neuen Teilnehmerrekord von \u00fcber 1000 Zillenbesatzungen. Wir gratulieren allen teilgenommenen Zillenbesatzungen f\u00fcr Ihre hervorragenden Leistungen. Besonders gratulieren d\u00fcrfen wir: 3.Platz Bronze allgemeine Klasse B:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1420","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts\/1420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/comments?post=1420"}],"version-history":[{"count":4,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts\/1420\/revisions"}],"predecessor-version":[{"id":1543,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts\/1420\/revisions\/1543"}],"wp:attachment":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/media?parent=1420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/categories?post=1420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/tags?post=1420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}