{"id":1856,"date":"2018-07-19T18:00:35","date_gmt":"2018-07-19T16:00:35","guid":{"rendered":"http:\/\/afk-lembach.at\/niederranna\/?p=1856"},"modified":"2018-11-08T10:58:13","modified_gmt":"2018-11-08T09:58:13","slug":"taucherlager-der-tauchgruppe-niederranna-2018","status":"publish","type":"post","link":"https:\/\/afk-lembach.at\/niederranna\/2018\/07\/19\/taucherlager-der-tauchgruppe-niederranna-2018\/","title":{"rendered":"Taucherlager der Tauchgruppe Niederranna 2018"},"content":{"rendered":"<p>Auch im heurigen Jahr war das Taucherlager der Tauchgruppe Niederranna in Weyregg am Attersee ein voller Erfolg.<\/p>\n<p>Es nahmen insgesamt 14 Einsatztaucher und 2 G\u00e4stetaucher an den \u00dcbungen (Wechselatmung, Notaufstieg, Nachttauchgang, usw.) vom 15.07. bis 19.07.2018 bei verh\u00e4ltnism\u00e4\u00dfig schlechter Sicht im Attersee teil.<\/p>\n<p>Das unter Wasser Erlebte wurde nat\u00fcrlich anschlie\u00dfend ausf\u00fchrlich in gem\u00fctlicher Runde besprochen und Erfahrungen weiter gegeben.<\/p>\n<p>Um den Familien der Taucher und deren Unterst\u00fctzern etwas zur\u00fcckgeben zu k\u00f6nnen, bot die Tauchgruppe auch heuer wieder die M\u00f6glichkeit an, am Ausbildungsgel\u00e4nde des LFK O\u00d6 miteinander Zeit zu verbringen. Man wei\u00df ja nie, wann und wo sich ein neuer Tauchanw\u00e4rter findet.<\/p>\n<p>In diesem Sinne: \u201eGut Luft!\u201c<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/afk-lembach.at\/niederranna\/bilder\/nggallery\/alles\/taucherlager-2018\">Bilder<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch im heurigen Jahr war das Taucherlager der Tauchgruppe Niederranna in Weyregg am Attersee ein voller Erfolg. Es nahmen insgesamt 14 Einsatztaucher und 2 G\u00e4stetaucher an den \u00dcbungen (Wechselatmung, Notaufstieg, Nachttauchgang, usw.) vom 15.07. bis 19.07.2018 bei verh\u00e4ltnism\u00e4\u00dfig schlechter Sicht im Attersee teil. Das unter Wasser Erlebte wurde nat\u00fcrlich anschlie\u00dfend ausf\u00fchrlich in gem\u00fctlicher Runde besprochen [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1856","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts\/1856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/comments?post=1856"}],"version-history":[{"count":4,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts\/1856\/revisions"}],"predecessor-version":[{"id":1952,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/posts\/1856\/revisions\/1952"}],"wp:attachment":[{"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/media?parent=1856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/categories?post=1856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afk-lembach.at\/niederranna\/wp-json\/wp\/v2\/tags?post=1856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}